{"id":1906,"date":"2015-09-19T18:04:41","date_gmt":"2015-09-19T16:04:41","guid":{"rendered":"http:\/\/kathrinfutter.ch\/blog\/?p=1906"},"modified":"2015-09-19T18:04:41","modified_gmt":"2015-09-19T16:04:41","slug":"buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten","status":"publish","type":"post","link":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten","title":{"rendered":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_1906 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_1906')){$('.twoclick_social_bookmarks_post_1906').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\",\"post_id\":1906,\"post_title_referrer_track\":\"Buchtipp+14%3A+Abschlussarbeiten+im+Studium+anleiten%2C+betreuen+und+bewerten\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p>Gestern Abend war ich an einer Buchvernissage der besonderen Art! Die Fachstelle f\u00fcr <a href=\"http:\/\/www.hochschuldidaktik.uzh.ch\/index.html\" target=\"_blank\">Hochschuldidaktik<\/a> der Universit\u00e4t Z\u00fcrich hat eingeladen, um das eben erschienene Buch von <a href=\"http:\/\/www.hochschuldidaktik.uzh.ch\/aboutus\/team\/buffKeller-eva.html\" target=\"_blank\">Eva Buff Keller<\/a> und <a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/joes\/\" target=\"_blank\">Stefan J\u00f6rissen<\/a> zu w\u00fcrdigen. Dies geschah, indem zuerst zwei Frauen des <a href=\"http:\/\/www.forumtheater.ch\/\" target=\"_blank\">Forumtheaters<\/a> verschiedene Szenen spielten: eine Assistentin und eine Studentin die sich mehrmals treffen, wobei der Abgabetermin der Arbeit immer n\u00e4her r\u00fcckt und die Arbeit nicht recht vom Fleck kommen will&#8230; Sodann konnte sich das Publikum beteiligen und versuchen, der Situation eine andere Richtung zu geben. Es wurde viel gelacht und Fazit war, dass es wohl am besten gewesen w\u00e4re, die Assistentin h\u00e4tte das <a href=\"http:\/\/www.hochschuldidaktik.uzh.ch\/veranstaltungen\/news\/Buchneuerscheinung.html\" target=\"_blank\">Buch<\/a> vorher gelesen. Hier der Klappentext:<\/p>\n<p><a href=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2015\/09\/Arbeiten.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1907\" src=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2015\/09\/Arbeiten.jpg\" alt=\"Arbeiten\" width=\"150\" height=\"213\" \/><\/a>F\u00fcr das Verfassen von Abschlussarbeiten, aber auch von Seminar- oder Hausarbeiten w\u00e4hrend des Studiums ben\u00f6tigen Studierende neben fachlichen auch \u00fcberfachliche Kompetenzen, etwa im bereich der Projektplanung und des wissenschaftlichen Schreibens. Eva Buff Keller und Stefan J\u00f6rissen zeigen praxisnah auf, wie solche Kompetenzen systematische gef\u00f6rdert, wie schriftliche Arbeiten effektiv begleitet und wie sie sinnvoll bewertet werden k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Ich fand die Lekt\u00fcre sehr anregend! Die 100 Seiten lesen sich fl\u00fcssig und es kommen tats\u00e4chlich sehr viele praxisnahe Beispiele als auch Vorschl\u00e4ge zum Zug. Trotzdem ist die theoretische Einbettung vorhanden und Rahmenbedingen, Dimensionen und Ebenen der Begleitung von Studierenden werden systematisch dargestellt.<\/p>\n<p><strong>Quelle:<\/strong> Buff Keller, E. &amp; J\u00f6rissen, S. (2015). Abschlussarbeiten im Studium anleiten, betreuen und bewerten. Opaden &amp; toronto: Verlag Barbara Budrich. Auch als <a href=\"http:\/\/www.utb-shop.de\/abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten-8444.html\" target=\"_blank\">E-Book<\/a> erh\u00e4ltlich!<\/p>","protected":false},"excerpt":{"rendered":"<p>Gestern Abend war ich an einer Buchvernissage der besonderen Art! Die Fachstelle f\u00fcr Hochschuldidaktik der Universit\u00e4t Z\u00fcrich hat eingeladen, um das eben erschienene Buch von Eva Buff Keller und Stefan J\u00f6rissen zu w\u00fcrdigen. Dies geschah, indem zuerst zwei Frauen des &hellip; <a href=\"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12,83],"tags":[242,243],"class_list":["post-1906","post","type-post","status-publish","format-standard","hentry","category-didaktik","category-hochschullehre","category-universitat","tag-abschlussarbeiten","tag-betreuung"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bildungsfutter |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-19T16:04:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-19T16:04:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#article\",\"name\":\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter\",\"headline\":\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten\",\"author\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Arbeiten.jpg\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\\\/#articleImage\",\"width\":150,\"height\":213},\"datePublished\":\"2015-09-19T18:04:41+02:00\",\"dateModified\":\"2015-09-19T18:04:41+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage\"},\"articleSection\":\"Didaktik, Hochschullehre, Universit\\u00e4t, Abschlussarbeiten, Betreuung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"name\":\"Didaktik\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"position\":2,\"name\":\"Didaktik\",\"item\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#listItem\",\"name\":\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#listItem\",\"position\":3,\"name\":\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"name\":\"Didaktik\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\",\"name\":\"Bildungsfutter\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#authorImage\",\"url\":\"http:\\\/\\\/1.gravatar.com\\\/avatar\\\/d93de0e4ac2f0c3ee0c2bb35e714aae3?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\",\"name\":\"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"datePublished\":\"2015-09-19T18:04:41+02:00\",\"dateModified\":\"2015-09-19T18:04:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/\",\"name\":\"Bildungsfutter\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter","description":"","canonical_url":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#article","name":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter","headline":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten","author":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"publisher":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2015\/09\/Arbeiten.jpg","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten\/#articleImage","width":150,"height":213},"datePublished":"2015-09-19T18:04:41+02:00","dateModified":"2015-09-19T18:04:41+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage"},"isPartOf":{"@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage"},"articleSection":"Didaktik, Hochschullehre, Universit\u00e4t, Abschlussarbeiten, Betreuung"},{"@type":"BreadcrumbList","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog#listItem","position":1,"name":"Home","item":"http:\/\/kathrinfutter.ch\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","name":"Didaktik"}},{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","position":2,"name":"Didaktik","item":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik","nextItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#listItem","name":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten"},"previousItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#listItem","position":3,"name":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten","previousItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","name":"Didaktik"}}]},{"@type":"Organization","@id":"http:\/\/kathrinfutter.ch\/blog\/#organization","name":"Bildungsfutter","url":"http:\/\/kathrinfutter.ch\/blog\/"},{"@type":"Person","@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author","url":"http:\/\/kathrinfutter.ch\/blog\/author\/admin","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#authorImage","url":"http:\/\/1.gravatar.com\/avatar\/d93de0e4ac2f0c3ee0c2bb35e714aae3?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#webpage","url":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten","name":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter","inLanguage":"de-DE","isPartOf":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten#breadcrumblist"},"author":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"creator":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"datePublished":"2015-09-19T18:04:41+02:00","dateModified":"2015-09-19T18:04:41+02:00"},{"@type":"WebSite","@id":"http:\/\/kathrinfutter.ch\/blog\/#website","url":"http:\/\/kathrinfutter.ch\/blog\/","name":"Bildungsfutter","inLanguage":"de-DE","publisher":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Bildungsfutter |","og:type":"article","og:title":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter","og:url":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten","article:published_time":"2015-09-19T16:04:41+00:00","article:modified_time":"2015-09-19T16:04:41+00:00","twitter:card":"summary","twitter:title":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten | Bildungsfutter"},"aioseo_meta_data":{"post_id":"1906","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-08 09:43:24","updated":"2025-06-03 23:42:57","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/kathrinfutter.ch\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik\" title=\"Didaktik\">Didaktik<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBuchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/kathrinfutter.ch\/blog"},{"label":"Didaktik","link":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik"},{"label":"Buchtipp 14: Abschlussarbeiten im Studium anleiten, betreuen und bewerten","link":"http:\/\/kathrinfutter.ch\/blog\/buchtipp-14-abschlussarbeiten-im-studium-anleiten-betreuen-und-bewerten"}],"_links":{"self":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/1906"}],"collection":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/comments?post=1906"}],"version-history":[{"count":5,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/1906\/revisions"}],"predecessor-version":[{"id":1912,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/1906\/revisions\/1912"}],"wp:attachment":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/media?parent=1906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/categories?post=1906"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/tags?post=1906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}