{"id":383,"date":"2009-09-28T12:25:47","date_gmt":"2009-09-28T18:25:47","guid":{"rendered":"http:\/\/kathrinfutter.ch\/blog\/?p=383"},"modified":"2009-09-28T12:25:47","modified_gmt":"2009-09-28T18:25:47","slug":"quassum-projektmanagement-tool","status":"publish","type":"post","link":"http:\/\/kathrinfutter.ch\/blog\/quassum-projektmanagement-tool","title":{"rendered":"Quassum | Projektmanagement-Tool"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_383 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_383')){$('.twoclick_social_bookmarks_post_383').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/quassum-projektmanagement-tool\",\"post_id\":383,\"post_title_referrer_track\":\"Quassum+%7C+Projektmanagement-Tool\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-386\" title=\"Bild 3\" src=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/09\/Bild-31-300x154.png\" alt=\"Bild 3\" width=\"300\" height=\"154\" srcset=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/09\/Bild-31-300x154.png 300w, http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/09\/Bild-31.png 912w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Via\u00a0<a href=\"http:\/\/www.web2null.de\/\" target=\"_blank\">Web2Null<\/a> stiess ich auf\u00a0<a href=\"http:\/\/quassum.com\/\" target=\"_blank\">Quassum<\/a>, ein Projektmanagement-Tool, mit dem sich kleine Teams austauschen und ihre Aufgaben verwalten k\u00f6nnen. Kurzentschlossen installierte ich diese Software und begann f\u00fcr unser Forschungsteam darin Meilensteine zu erstellen und Tickets zu generieren. Das Instrument ist \u00e4usserst einfach und intuitiv zu bedienen und zudem ist es kostenlos!<\/p>\n<p>Wie es sich jedoch in der Praxis bew\u00e4hrt, wird sich erst noch weisen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Via\u00a0Web2Null stiess ich auf\u00a0Quassum, ein Projektmanagement-Tool, mit dem sich kleine Teams austauschen und ihre Aufgaben verwalten k\u00f6nnen. Kurzentschlossen installierte ich diese Software und begann f\u00fcr unser Forschungsteam darin Meilensteine zu erstellen und Tickets zu generieren. Das Instrument ist \u00e4usserst einfach &hellip; <a href=\"http:\/\/kathrinfutter.ch\/blog\/quassum-projektmanagement-tool\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[152],"class_list":["post-383","post","type-post","status-publish","format-standard","hentry","category-technik","tag-quassum-projektmanagement"],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/383"}],"collection":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":5,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/383\/revisions"}],"predecessor-version":[{"id":390,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/383\/revisions\/390"}],"wp:attachment":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/media?parent=383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/categories?post=383"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/tags?post=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}