{"id":398,"date":"2009-10-03T11:04:49","date_gmt":"2009-10-03T17:04:49","guid":{"rendered":"http:\/\/kathrinfutter.ch\/blog\/?p=398"},"modified":"2009-10-03T11:04:49","modified_gmt":"2009-10-03T17:04:49","slug":"selbst-organisiertes-lernen-sol","status":"publish","type":"post","link":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol","title":{"rendered":"Selbst organisiertes Lernen (SOL)"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_398 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_398')){$('.twoclick_social_bookmarks_post_398').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol\",\"post_id\":398,\"post_title_referrer_track\":\"Selbst+organisiertes+Lernen+%28SOL%29\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p>Gerne verweise ich an dieser Stelle auf zwei Publikationen der Bildungsdirektion des Kantons Z\u00fcrich, genauer des Mittelschul- und Berufsbildungsamtes, welche beide im Jahr 2009 erschienen sind (Downloadlink am Ende des Blogbeitrags):<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-399\" title=\"Bild 1\" src=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-1-300x207.png\" alt=\"Bild 1\" width=\"300\" height=\"207\" srcset=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-1-300x207.png 300w, http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-1.png 901w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-400\" title=\"Bild 2\" src=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-2-300x206.png\" alt=\"Bild 2\" width=\"300\" height=\"206\" srcset=\"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-2-300x206.png 300w, http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-2.png 914w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Beide Brosch\u00fcren befassen sich mit dem selbst organisierten Lernen SOL an Gymnasien. In der oben abgebildeten findet man s\u00e4mtliche Unterlagen, die von der Projektgruppe SOL sowie vom Institut f\u00fcr Gymnasial- und Berufsp\u00e4dagogik der Universit\u00e4t Z\u00fcrich f\u00fcr das Projekt SOL (2008-2011) bis zum aktuellen Zeitpunkt (Juni 2009) erstellt worden sind. Laut Vorwort sollen die Dokumente den schulinternen Projektteams sowie den Fachschaften und dem ganzen Lehrerteam einer Schule dazu dienen, sich ein Bild \u00fcber selbst organisiertes Lernen machen zu k\u00f6nnen. Zudem werden in der Brosch\u00fcre Vorschl\u00e4ge und Ideen vermittelt, wie ein solches Projekt durchgef\u00fchrt werden k\u00f6nnte.<\/p>\n<p>Die unten\u00a0abgebildete Brosch\u00fcre &#8211; welche als Handreichung bezeichnet wird &#8211; schildert Besonderheiten der Leistungsbeurteilung in Unterrichtssequenzen mit selbst organisiertem Lernen, \u00abindem ihre Knackpunkte erl\u00e4utert, aber gleichzeitig L\u00f6sungsm\u00f6glichkeiten aufgezeigt und Materialien beigegeben werden\u00bb (vgl. S. 6). Die Autorinnen und Autoren der Handreichung sprechen von Leistungsbeurteilung in einem sehr weiten Sinn: Es geht um P\u00e4dagogische Diagnostik, welche auch die Funktion erf\u00fcllen soll, R\u00fcckmeldungen zur effektiven Steuerung von Lernprozessen zu liefern.<\/p>\n<p>Beide Brosch\u00fcren sind sehr \u00fcbersichtlich gestaltet, in einer klar verst\u00e4ndlichen Sprache geschrieben und meiner Ansicht nach sehr gut geeignet f\u00fcr Schulteams, welche selbst organisiertes Lernen unter den Sch\u00fclerinnen und Sch\u00fclern initiieren wollen.<\/p>\n<p><strong>Quellen:<\/strong><\/p>\n<p>Kyburz-Graber, R., Canella, C., Gerloff-Gasser, C. &amp; Pangrazzi, R. (2009): \u00dcberfachliche\u00a0Kompetenzen durch selbst organisiertes Lernen erwerben. Bildungsdirektion Z\u00fcrich. [<a href=\"http:\/\/www.mba.zh.ch\/downloads\/Projektstellen\/Dokumentensammlung.pdf\" target=\"_blank\">Download<\/a>]<\/p>\n<p>Winter, F. (2009). (Hrsg.) Leistungsbeurteilung in Projekten selbst organisierten Lernens. Eine Handreichung f\u00fcr Lehrpersonen an den Gymnasien des Kantons Z\u00fcrich. Bildungsdirektion Z\u00fcrich. [<a href=\"http:\/\/www.mba.zh.ch\/downloads\/Projektstellen\/Handreichung%20Leistungsbeurteilung.pdf\" target=\"_blank\">Download<\/a>]<\/p>","protected":false},"excerpt":{"rendered":"<p>Gerne verweise ich an dieser Stelle auf zwei Publikationen der Bildungsdirektion des Kantons Z\u00fcrich, genauer des Mittelschul- und Berufsbildungsamtes, welche beide im Jahr 2009 erschienen sind (Downloadlink am Ende des Blogbeitrags): Beide Brosch\u00fcren befassen sich mit dem selbst organisierten Lernen &hellip; <a href=\"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,5,69],"tags":[154],"class_list":["post-398","post","type-post","status-publish","format-standard","hentry","category-bildung","category-didaktik","category-schule","tag-sol-mittelschule-leistungsbeurteilung"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bildungsfutter |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Selbst organisiertes Lernen (SOL) | Bildungsfutter\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2009-10-03T17:04:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2009-10-03T17:04:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Selbst organisiertes Lernen (SOL) | Bildungsfutter\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#article\",\"name\":\"Selbst organisiertes Lernen (SOL) | Bildungsfutter\",\"headline\":\"Selbst organisiertes Lernen (SOL)\",\"author\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/wp-content\\\/uploads\\\/2009\\\/10\\\/Bild-1.png\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol\\\/#articleImage\",\"width\":901,\"height\":623},\"datePublished\":\"2009-10-03T11:04:49+02:00\",\"dateModified\":\"2009-10-03T11:04:49+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#webpage\"},\"articleSection\":\"Bildung, Didaktik, Schule, SOL Mittelschule Leistungsbeurteilung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"name\":\"Didaktik\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"position\":2,\"name\":\"Didaktik\",\"item\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#listItem\",\"name\":\"Selbst organisiertes Lernen (SOL)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#listItem\",\"position\":3,\"name\":\"Selbst organisiertes Lernen (SOL)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/category\\\/didaktik#listItem\",\"name\":\"Didaktik\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\",\"name\":\"Bildungsfutter\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#authorImage\",\"url\":\"http:\\\/\\\/1.gravatar.com\\\/avatar\\\/d93de0e4ac2f0c3ee0c2bb35e714aae3?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#webpage\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol\",\"name\":\"Selbst organisiertes Lernen (SOL) | Bildungsfutter\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/selbst-organisiertes-lernen-sol#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/author\\\/admin#author\"},\"datePublished\":\"2009-10-03T11:04:49+02:00\",\"dateModified\":\"2009-10-03T11:04:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/\",\"name\":\"Bildungsfutter\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"http:\\\/\\\/kathrinfutter.ch\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Selbst organisiertes Lernen (SOL) | Bildungsfutter","description":"","canonical_url":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#article","name":"Selbst organisiertes Lernen (SOL) | Bildungsfutter","headline":"Selbst organisiertes Lernen (SOL)","author":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"publisher":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/kathrinfutter.ch\/blog\/wp-content\/uploads\/2009\/10\/Bild-1.png","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol\/#articleImage","width":901,"height":623},"datePublished":"2009-10-03T11:04:49+02:00","dateModified":"2009-10-03T11:04:49+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#webpage"},"isPartOf":{"@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#webpage"},"articleSection":"Bildung, Didaktik, Schule, SOL Mittelschule Leistungsbeurteilung"},{"@type":"BreadcrumbList","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog#listItem","position":1,"name":"Home","item":"http:\/\/kathrinfutter.ch\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","name":"Didaktik"}},{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","position":2,"name":"Didaktik","item":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik","nextItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#listItem","name":"Selbst organisiertes Lernen (SOL)"},"previousItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#listItem","position":3,"name":"Selbst organisiertes Lernen (SOL)","previousItem":{"@type":"ListItem","@id":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik#listItem","name":"Didaktik"}}]},{"@type":"Organization","@id":"http:\/\/kathrinfutter.ch\/blog\/#organization","name":"Bildungsfutter","url":"http:\/\/kathrinfutter.ch\/blog\/"},{"@type":"Person","@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author","url":"http:\/\/kathrinfutter.ch\/blog\/author\/admin","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#authorImage","url":"http:\/\/1.gravatar.com\/avatar\/d93de0e4ac2f0c3ee0c2bb35e714aae3?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#webpage","url":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol","name":"Selbst organisiertes Lernen (SOL) | Bildungsfutter","inLanguage":"de-DE","isPartOf":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol#breadcrumblist"},"author":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"creator":{"@id":"http:\/\/kathrinfutter.ch\/blog\/author\/admin#author"},"datePublished":"2009-10-03T11:04:49+02:00","dateModified":"2009-10-03T11:04:49+02:00"},{"@type":"WebSite","@id":"http:\/\/kathrinfutter.ch\/blog\/#website","url":"http:\/\/kathrinfutter.ch\/blog\/","name":"Bildungsfutter","inLanguage":"de-DE","publisher":{"@id":"http:\/\/kathrinfutter.ch\/blog\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Bildungsfutter |","og:type":"article","og:title":"Selbst organisiertes Lernen (SOL) | Bildungsfutter","og:url":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol","article:published_time":"2009-10-03T17:04:49+00:00","article:modified_time":"2009-10-03T17:04:49+00:00","twitter:card":"summary","twitter:title":"Selbst organisiertes Lernen (SOL) | Bildungsfutter"},"aioseo_meta_data":{"post_id":"398","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-08 10:38:00","updated":"2025-06-03 23:33:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/kathrinfutter.ch\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik\" title=\"Didaktik\">Didaktik<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSelbst organisiertes Lernen (SOL)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/kathrinfutter.ch\/blog"},{"label":"Didaktik","link":"http:\/\/kathrinfutter.ch\/blog\/category\/didaktik"},{"label":"Selbst organisiertes Lernen (SOL)","link":"http:\/\/kathrinfutter.ch\/blog\/selbst-organisiertes-lernen-sol"}],"_links":{"self":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/398"}],"collection":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":7,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"predecessor-version":[{"id":407,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/posts\/398\/revisions\/407"}],"wp:attachment":[{"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/kathrinfutter.ch\/blog\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}